{"id":268,"date":"2023-01-05T19:11:38","date_gmt":"2023-01-05T19:11:38","guid":{"rendered":"https:\/\/werkalecinmuebles.com.ar\/?p=268"},"modified":"2023-01-08T19:32:46","modified_gmt":"2023-01-08T19:32:46","slug":"la-rentabilidad-de-la-vivienda-en-espana-crece-en-2022","status":"publish","type":"post","link":"https:\/\/werkalecinmuebles.com.ar\/index.php\/2023\/01\/05\/la-rentabilidad-de-la-vivienda-en-espana-crece-en-2022\/","title":{"rendered":"La rentabilidad de la vivienda en Espa\u00f1a crece en 2022"},"content":{"rendered":"<blockquote>\n<h2>A nivel nacional, las oficinas siguen siendo el producto m\u00e1s rentable (12,9%), seguido de locales (9,6%) y garajes (7,1%)<\/h2>\n<\/blockquote>\n<p>La rentabilidad bruta de la compra de una vivienda para ponerla en el mercado del alquiler ha crecido ligeramente durante el cuarto trimestre hasta el 7,2%, ya que a cierre de 2021 el retorno que ofrec\u00eda se situaba en el 6,9%. Seg\u00fan el&nbsp;<strong>estudio realizado por idealista<\/strong>, la rentabilidad obtenida duplica, en el peor de los casos, las tasas que ofrecen los Bonos del Estado a 10 a\u00f1os (3,5%).<\/p>\n<p>Seg\u00fan este estudio, que relaciona los precios de venta y alquiler de distintos productos inmobiliarios para calcular su rentabilidad bruta,&nbsp;<strong>las oficinas se mantienen como la inversi\u00f3n inmobiliaria m\u00e1s rentable<\/strong>. Comprar una oficina en Espa\u00f1a para alquilarla ofrece una rentabilidad bruta del 12,9%, frente al 11,2% que daba hace 12 meses. Los locales ofrecen un rendimiento del 9,6% (9,4% hace un a\u00f1o) y en el caso de los garajes se sit\u00faa en el 7,1%, superior al 6% de diciembre de 2021.<\/p>\n<h2>Rentabilidad de la vivienda<\/h2>\n<p>Entre las capitales espa\u00f1olas, Lleida es la que resulta m\u00e1s rentable, ya que alcanza el 8,3%, seguida por la ciudad de Murcia con un 8,2% y Huelva (8,1%). Con rentabilidades inferiores al 8% se sit\u00faan Teruel (7,3%), Ja\u00e9n (7,3%), Almer\u00eda (7,1%), Castell\u00f3n de la Plana y Alicante (7% en ambos casos). Por el contrario, San Sebasti\u00e1n es la ciudad donde la rentabilidad es m\u00e1s reducida (3,8%), seguida por Palma (4,3%), A Coru\u00f1a (4,6%), Pamplona (4,7%) y Madrid (4,9%). En Barcelona, la rentabilidad llega hasta el 5,7%.<\/p>\n<h2>Rentabilidad de los locales comerciales<\/h2>\n<p>Los locales son el producto que mayor rentabilidad tiene en casi todas las capitales. El mayor retorno se obtiene en Santa Cruz de Tenerife (11%), Lleida y \u00c1vila (10,7% en ambos casos). Le siguen las rentabilidades de Huelva y Lugo (10,6% en las dos ciudades), Zaragoza (10,5%), Girona y Murcia (10,1%). En Barcelona la tasa se sit\u00faa en el 8,6% y en Madrid se queda en el 8%.<\/p>\n<p>Salamanca es la capital en la que la rentabilidad de los locales es menor, con un 7,4%. La parte baja de la tabla se completa con Albacete (7,5%), Segovia, Ja\u00e9n y A Coru\u00f1a (7,6% en los tres casos).<\/p>\n<h2>Rentabilidad de las oficinas<\/h2>\n<p>Las oficinas de Sevilla presentan el retorno m\u00e1s jugoso entre las capitales, con un 13,4% de rentabilidad bruta. Le siguen Zaragoza (10,8%), Albacete (10,6%), Almer\u00eda (10,3%) y Vitoria (9,3%). En Barcelona, la rentabilidad se sit\u00faa en el 7,3%.<\/p>\n<p>En el lado opuesto encontramos las rentabilidades de Bilbao (6,2%), Santa Cruz de Tenerife (6,2%), A Coru\u00f1a (6,3%), Madrid, C\u00f3rdoba, Pamplona y Ourense (6,6% en las cuatro ciudades). El mercado de oficinas no es tan uniforme como el de otros productos, por lo que resulta imposible obtener datos estad\u00edsticos de casi la mitad de capitales espa\u00f1olas.<\/p>\n<h2>Rentabilidad de los garajes<\/h2>\n<p>Los garajes son, en contraposici\u00f3n, el producto menos rentable para el inversor en muchas capitales. La mayor rentabilidad se obtiene en Murcia (9,4%), Castell\u00f3n de la Plana (8,6%), \u00c1vila (7,5%), Lleida (7,2%), Palma (6,8%), Toledo (6,5%) y Barcelona (6,5%). En Madrid, la tasa de retorno se sit\u00faa en el 5,2%.<\/p>\n<p>La capital con los garajes menos rentables es Salamanca, con un 2,9%, seguida por Ourense (3%), Santander (3,2%), Palencia (3,5%), Granada y Vitoria (con sendas rentabilidades del 3,7%). &nbsp;<\/p>\n<figure id=\"attachment_269\" aria-describedby=\"caption-attachment-269\" style=\"width: 942px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-269 size-full\" src=\"https:\/\/werkalecinmuebles.com.ar\/wp-content\/uploads\/2023\/01\/Captura-de-pantalla_20230107_161354.png\" alt=\"\" width=\"942\" height=\"770\" srcset=\"https:\/\/werkalecinmuebles.com.ar\/wp-content\/uploads\/2023\/01\/Captura-de-pantalla_20230107_161354.png 942w, https:\/\/werkalecinmuebles.com.ar\/wp-content\/uploads\/2023\/01\/Captura-de-pantalla_20230107_161354-300x245.png 300w, https:\/\/werkalecinmuebles.com.ar\/wp-content\/uploads\/2023\/01\/Captura-de-pantalla_20230107_161354-768x628.png 768w\" sizes=\"auto, (max-width: 942px) 100vw, 942px\" \/><figcaption id=\"caption-attachment-269\" class=\"wp-caption-text\">* &#8211; Falta una oferta m\u00ednima en el mercado para ofrecer el dato ajustado CONSULTAR LA FUENTE (Al pie de la pagina) PARA PODER VER EL INFORME COMPLETO Fuente: idealista Descargar los datos Creado con Datawrapper<\/figcaption><\/figure>\n<p><strong>Metodolog\u00eda<\/strong><\/p>\n<p>Para la elaboraci\u00f3n de este estudio, idealista ha dividido el precio de venta ofertado entre el precio de alquiler que solicitan los propietarios en los diferentes mercados referente a los \u00edndices trimestrales de viviendas, locales, garajes y oficinas correspondientes al cuarto trimestre de 2022. El resultado obtenido es el porcentaje bruto de rentabilidad que proporciona a un propietario alquilar su vivienda. Este dato facilita el an\u00e1lisis del estado actual del mercado y es un punto de partida b\u00e1sico para todos aquellos inversores que quieran comprar activos inmobiliarios con el fin de obtener beneficios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rentabilidad bruta de la compra de una vivienda para ponerla en el mercado del alquiler ha crecido ligeramente durante el cuarto trimestre hasta el 7,2%, ya que a cierre de 2021 el retorno que ofrec\u00eda se situaba en el 6,9%.<\/p>\n","protected":false},"author":1,"featured_media":270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[15,3],"tags":[20,5,6,16,19],"class_list":["post-268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informes","category-prensa","tag-alquiler","tag-espana","tag-informes","tag-inmuebles","tag-mercado-inmobiliario"],"acf":[],"_links":{"self":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=268"}],"version-history":[{"count":2,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/268\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/268\/revisions\/282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/media\/270"}],"wp:attachment":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}