{"id":40,"date":"2021-07-27T14:01:51","date_gmt":"2021-07-27T14:01:51","guid":{"rendered":"https:\/\/werkalecinmuebles.com.ar\/?p=40"},"modified":"2022-01-06T14:07:41","modified_gmt":"2022-01-06T14:07:41","slug":"por-que-hay-un-boom-de-argentinos-que-invierten-en-espana","status":"publish","type":"post","link":"https:\/\/werkalecinmuebles.com.ar\/index.php\/2021\/07\/27\/por-que-hay-un-boom-de-argentinos-que-invierten-en-espana\/","title":{"rendered":"Por qu\u00e9 hay un boom de argentinos que invierten en Espa\u00f1a"},"content":{"rendered":"<h2 class=\"com-subhead --bajada --m-xs\">La Argentina entr\u00f3 por primera vez en el ranking de compradores extranjeros de inmuebles en el pa\u00eds europeo: representan el 1% de las escrituras firmadas en el primer trimestre del a\u00f1o<\/h2>\n<p>En plena pandemia de coronavirus, el mercado inmobiliario espa\u00f1ol incorpor\u00f3 entre sus filas a cientos de compradores extranjeros. En el ranking, predominan los europeos y, por primera vez,\u00a0<strong>los argentinos se asoman en la lista y se convierten en los \u00fanicos latinoamericanos en formar parte de la estad\u00edstica.\u00a0<\/strong>\u00bfLos destinos predilectos? Madrid, Barcelona, Alicante y M\u00e1laga.<\/p>\n<p class=\"com-paragraph   --s\">Seg\u00fan un informe de Reporte Inmobiliario, en el primer trimestre de 2021,\u00a0<strong>en Espa\u00f1a se vendieron 129.228 viviendas,<\/strong>\u00a0lo que signific\u00f3 un aumento del 13,6% con respecto al \u00faltimo trimestre de 2020. Del total de esas operaciones,\u00a0<strong>casi el 10% fueron realizadas por extranjeros,\u00a0<\/strong>de acuerdo con los datos difundidos por el Colegio de Registradores del pa\u00eds. A esa lista, encabezada por compradores brit\u00e1nicos, marroqu\u00edes, franceses y alemanes, en esta oportunidad se sumaron los argentinos, con casi el 1% del total de escrituras firmadas.<\/p>\n<p>En total, durante los primeros tres meses del a\u00f1o,\u00a0<strong>119 viviendas fueron compradas por argentinos.<\/strong>\u00a0\u201cEs la primera vez que el pa\u00eds entra en la estad\u00edstica de los registradores espa\u00f1oles y tambi\u00e9n la primera vez que lo hace una naci\u00f3n latinoamericana y esto teniendo en cuenta que, en este momento, pr\u00e1cticamente no se puede viajar\u201d, remarc\u00f3 Germ\u00e1n G\u00f3mez Picasso, fundador de <a href=\"https:\/\/www.reporteinmobiliario.com\/nuke\/index.php\">Reporte Inmobiliario<\/a>.<\/p>\n<p>Sobre esta nueva tendencia, Jos\u00e9 Rozados, director de Reporte Inmobiliario y quien estuvo a cargo del informe, asegur\u00f3 en di\u00e1logo con <a href=\"https:\/\/www.lanacion.com.ar\/propiedades\/inversiones\/boom-de-argentinos-que-invierten-en-espana-nid27072021\/\">LA NACION<\/a>:<strong>\u00a0\u201cHay una nueva oleada de emigraci\u00f3n de argentinos a Espa\u00f1a.\u00a0<\/strong>Fundamentalmente, son profesionales o gente con recursos que en muchos casos dispone de capital o se desprende de inmuebles en la Argentina para emprender en otro continente\u201d.<\/p>\n<p class=\"com-paragraph   --s\">El aumento de compradores argentinos no solo tiene que ver con aquellos que deciden mudarse a otro pa\u00eds y eligen Espa\u00f1a como su destino, sino tambi\u00e9n con quienes ven\u00a0<strong>una posibilidad de inversi\u00f3n por la alta rentabilidad que se obtiene a partir del alquiler de una vivienda.\u00a0<\/strong>Seg\u00fan se\u00f1al\u00f3 Rozados, en Madrid, la rentabilidad de un alquiler tradicional gira en torno al 5% anual, muy por encima del 2,71% bruto que\u00a0<a class=\"com-link\" title=\"consigue un propietario porte\u00f1o.\" href=\"https:\/\/www.lanacion.com.ar\/propiedades\/casas-y-departamentos\/aunque-se-venia-recuperando-un-alquiler-rinde-la-mitad-que-en-2017-nid10062021\/\" target=\"_self\" data-reactroot=\"\" rel=\"noopener\">consigue un propietario porte\u00f1o.<\/a>\u00a0En zonas tur\u00edsticas, la cifra puede superar el 7% anual.<\/p>\n<p class=\"com-paragraph   --s\"><strong>Madrid, Barcelona, Alicante y M\u00e1laga son los destinos m\u00e1s elegidos por los argentinos\u00a0<\/strong>y los\u00a0<em>brokers\u00a0<\/em>del mercado hispano sostienen que la cifra de compradores seguir\u00e1 creciendo, de acuerdo con las operaciones ya confirmadas y el importante aumento de consultas que reciben a diario. Con este panorama, Espa\u00f1a se posiciona lentamente como el nuevo lugar de preferencia de los compradores del pa\u00eds.<\/p>\n<h3 class=\"com-title --m\">El mercado inmobiliario en Espa\u00f1a<\/h3>\n<p class=\"com-paragraph   --s\">Pese a que el primer trimestre dej\u00f3 un escenario complejo por el avance del coronavirus en pleno invierno,\u00a0<strong>el n\u00famero de compraventas de viviendas en Espa\u00f1a super\u00f3 al registrado en el mismo per\u00edodo de 2020,\u00a0<\/strong>cuando el mercado no estaba afectado por la crisis sanitaria. La recuperaci\u00f3n del sector inmobiliario parece afianzarse y las expectativas de crecimiento crecen de cara a la pospandemia.<\/p>\n<p class=\"com-paragraph   --s\">\u00bfHay oportunidades para los argentinos que piensan en comprar una propiedad en el pa\u00eds europeo? Seg\u00fan Rozados,<strong>\u00a0el monto m\u00ednimo que se necesita para empezar a buscar una vivienda en Espa\u00f1a es de US$120.000.<\/strong>\u00a0\u201cPor supuesto que hay opciones m\u00e1s baratas en localizaciones secundarias en ciudades peque\u00f1as, pero ese es el n\u00famero que hay que tener en la cabeza para pensar en acceder a un departamento propio\u201d, indic\u00f3 el especialista.<\/p>\n<p class=\"com-paragraph   --s\">Las ventajas son una buena rentabilidad y una proyecci\u00f3n de valorizaci\u00f3n del inmueble. En tanto, Rozados remarc\u00f3 que, en Espa\u00f1a, al igual que en otras partes del mundo,\u00a0<strong>se gener\u00f3 en el \u00faltimo tiempo un marcado inter\u00e9s por las zonas rurales y semirurales<\/strong>\u00a0que tienen buenas v\u00edas de acceso y no se encuentran a m\u00e1s de 30 minutos de las ciudades. \u201cAll\u00ed hay m\u00e1s oportunidades a mejores valores, pero en general hay que estar dispuesto a encarar remodelaciones y a vivir en un entorno natural. Sin embargo, es una opci\u00f3n por la que cada vez m\u00e1s poblaci\u00f3n urbana est\u00e1 optando\u201d, asegur\u00f3.<\/p>\n<p><strong>FUENTE:<\/strong>\u00a0 <a href=\"https:\/\/www.lanacion.com.ar\/propiedades\/inversiones\/boom-de-argentinos-que-invierten-en-espana-nid27072021\/\">La Naci\u00f3n<\/a> by <a href=\"https:\/\/www.lanacion.com.ar\/autor\/delfina-casali\/\">Delfina Casali<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Argentina entr\u00f3 por primera vez en el ranking de compradores extranjeros de inmuebles en el pa\u00eds europeo: representan el 1% de las escrituras firmadas en el primer trimestre del a\u00f1o En plena pandemia de coronavirus, el mercado inmobiliario espa\u00f1ol incorpor\u00f3 entre sus filas a cientos de compradores extranjeros. En el ranking, predominan los europeos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[5,6,4,7],"class_list":["post-40","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa","tag-espana","tag-informes","tag-inversion","tag-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":1,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"predecessor-version":[{"id":41,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/40\/revisions\/41"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/media\/29"}],"wp:attachment":[{"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/werkalecinmuebles.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}